{"id":170,"date":"2013-07-09T15:30:36","date_gmt":"2013-07-09T15:30:36","guid":{"rendered":"https:\/\/wp.rhythms-of-resistance.org\/?p=170"},"modified":"2019-05-30T15:31:51","modified_gmt":"2019-05-30T15:31:51","slug":"espanol-mas-orgullosas-que-nunca","status":"publish","type":"post","link":"https:\/\/www.rhythms-of-resistance.org\/he\/2013\/07\/09\/espanol-mas-orgullosas-que-nunca\/","title":{"rendered":"M\u00e1s orgullosas que nunca"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-he\">\u05de\u05e6\u05d8\u05e2\u05e8\u05d9\u05dd, \u05e8\u05e9\u05d5\u05de\u05d4 \u05d6\u05d5 \u05d6\u05de\u05d9\u05e0\u05d4 \u05e8\u05e7 \u05d1- <a href=\"https:\/\/www.rhythms-of-resistance.org\/es\/wp-json\/wp\/v2\/posts\/170\" class=\"qtranxs-available-language-link qtranxs-available-language-link-es\" title=\"Espa\u00f1ol\">Espa\u00f1ol<\/a>.<\/p><p>D.Redondo<\/p>\n<p>\u2018Direni\u015f\u2019 -que en turco significa &quot;resistencia&quot;- es el eslogan de este a\u00f1o para la semana del Orgullo en Estambul. Las protestas contra la destruccion del parque Gezi, como emblema de la creceinte politica neoliberal de la politica del partido del gobierno y su tendencia a la restriccion de los derechos civiles, han s\u0131do el centro tambien de las manifestaciones de los colectivos LGBT (Lesbianas, gays, bisexuales y transexuales).<\/p>\n<p>Desde su inicio en 2003, la manifestacion del Orgullo en Estambul no ha seguido los canones europeos marcados por suntuosos desfiles de carrozas, enormes equipos de sonidos y celebridades saludando en sus mejores galas, sino que tiene un estilo DIY (do-it-yourself) propio de las acciones que parten de la iniciativa colectiva. Tambien debido a que nunca han pedido permiso para salir a la calle a manifestarse ni cuentan con el apoyo del gobierno para celebrarlo. El primer a\u00f1o se juntaron unas 50 personas, un numero escaso para una ciudad con mas 14 millones de habitanes, pero sirvio como precedente para iniciar una tradicion que cada a\u00f1o congrega a mas gente, de Turquia, pero tambien de otros paises, fundamentalmente Iran, Palestina, Israel o Siria. En 2010 se estiman que participaron mas de 5000; en 2011, 10.000, y este a\u00f1o mas de 15.000 personas.<\/p>\n<h3 class=\"spip\">De Gezi al Orgullo<\/h3>\n<p>&quot;El exito de la convocatoria de la semana del Orgullo ha sido impresionante. La gente ha estado mas unida que nunca y los eslogans han sido mucho mas politicos que en a\u00f1os anteriores&quot;, comenta una manifestante. El grupo LGBT ha estado muy presente durante la ocupacion del parque Gezi. De manera espontanea alguien colgo una bandera arcoiris en una tienda y de ahi surgio un bloque activista LGBT dentro de la acampada y en seguida comenzo a recibir el apoyo de la gente (mesas, tiendas, comida&#8230;). Esto ha servido como punto de inflexion para muchas personas que nunca antes habian tratado con personas transexuales u homosexuales y que tenian numerosos prejucios sobre ellas propios del desconocimiento. &quot;Al principio teniamos esloganes homofobicos contra la policia&quot;, relata un participante en las conferencias de la semana del Orgullo, &quot;nunca antes me lo hubiera planteado, pero al ver a ese grupo de gente nos dimos cuenta de que habia que cambiar nuestras consignas porque no podiamos burlarnos de la gente con la que estabamos luchando&quot;.<\/p>\n<p><span class=\"spip_document_529 spip_documents spip_documents_center\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-171 aligncenter\" src=\"https:\/\/www.rhythms-of-resistance.org\/wp-content\/uploads\/2019\/05\/toma_agua_-2.jpg\" alt=\"\" width=\"488\" height=\"286\" srcset=\"https:\/\/www.rhythms-of-resistance.org\/wp-content\/uploads\/2019\/05\/toma_agua_-2.jpg 488w, https:\/\/www.rhythms-of-resistance.org\/wp-content\/uploads\/2019\/05\/toma_agua_-2-300x176.jpg 300w\" sizes=\"(max-width: 488px) 85vw, 488px\" \/><\/span>Este mes de lucha y resistencia hombro con hombro se ha notado en las dos manifestac\u0131ones. Primero, en la celebrada el dom\u0131ngo 24 de junio para apoyar los derechos de las personas transexuales, y despues en la manifestacion del 30 de jun\u0131o que cierra la semana del Orgullo. En todos lados se coreaba &quot;her yer Taksim, her yer direni\u015f&quot; (Taksim esta en todos lados, y en todos los lados resistimos), &quot;fashizme karsi bacak omuza&quot; (contra el fascismo, hombro con hombro), que deriva en pancartas tan creativas como &quot;la mejor manera de resistir el fascismo es poner tu pierna en su hombro&quot;, ilustrado con una postura del kamasutra. Otras proclamas durante las manifestaciones fueron &quot;translar burada, katilleri nerede?&quot;, (las personas transexuales estan aqui, donde estan sus asesinos?).<\/p>\n<h3 class=\"spip\">Mas Orgullosas que nunca<\/h3>\n<p>La plaza de Taksim fue el lugar de inicio de la manifestacion mas multitudinaria que pone fin a las semana de actividades, charlas, performances, acciones del Orgullo. Bajo la vigilancia de varios dispositivos policiales y los tanques TOMA (vehiculos de control de protesta), en un escenario de semidemolicion por las obras iniciadas en el lateral del parque se congregaron mas de 15.000 personas en direccion a Tunnel a traves de Istikal, la principal calle de tiendas de la ciudad. Personas vestidas de novia, vampiresas, acrobatas sobre las paradas de autobus&#8230;El ingenio de cada cual enriquece esta protesta. Como ya es habitual, la gente abucheo delante de la t\u0131enda de Mango, que en 2011 despidio a una persona por su orientacion sexual. En la embajada de Rusia se colgaron dos pancartas para expresar el rechazo ante la nueva politica homofobica y se colaron numerosos avioncitos de papel con mesajes de condena hacia la actitud intolerante del gobierno ruso. Delante de una iglesia catolica se grito mas fuerte que nunca el dialogo que es icono del Orgullo de este a\u00f1o: &quot;donde estas mi amor?, aqui estoy mi amor!&quot;, acompa\u00f1ada de gemidos de placer. Una presencia muy importante es el colect\u0131vo de familiares de LGBT, que 2012 fueron recibidos en el parlamento para defender los derechos de sus hijas e hijos. No faltaron banderas multicoles, pancartas, cada cual vestida o vestido como queria. Sin restricciones, sin normatividad.<\/p>\n<h3 class=\"spip\">La situacion LGBT en Turquia<\/h3>\n<p>Lambda Istanbul, promotora de la semana Orgullo y miembro de la federacion internacional LGBT, lleva desde 1933 luchando en Turquia por los derechos de las personas homosexuales,bisexuales y transexuales. En 2008 la asociacion fue acusada de prostitucion por el mero hecho de servir de punto de encuentro para transexuales y fue declarada ilegal. La sentencia fue recurrida y en la actuliadad continuan con su actividad. A pesar de que la ley no persigue la homosexualidad, los derechos de las distintas identidades sexuales no estan recogidos en la Constitucion. No se permite el matrimonio a personas del mismo sexo, ni se garantiza ningun derecho a la pareja ni se permite la adopcion. En el codigo militar la homosexualidad se considera una enfermedad &quot;psicosexual&quot; que incapacita a los hombres para realizar el servicio militar obligatorio. No hay leyes que protejan de la discriminacion sexual en el trabajo o en la educacion. Erdogan, el primer ministro turco, insto en unas declarac\u0131ones a las mujeres a tener &quot;tres hijos o mas&quot;, ya que, en su opinion, uno solo seria infeliz; dos, se pelearian, y a partir de tres es la cifra perfecta. Esta declaracion representa el patron heteronomativo imperante en la sociedad turca que, salvo en grandes urbes como Estambul, sigue siendo muy conservadora. Se estima que semanalmente solo en esta ciudad se porduce un &quot;asesinato de honor&quot; (normalmente practicados en la cultura islamica por la familia hacia las mujeres cuya conducta se considera inapropiada por su homosexualidad, o su vestimenta, o su negacion a un matrimonio concertado), segun datos de 2010 del Observatorio de los Derechos Humanos en Turquia.<\/p>","protected":false},"excerpt":{"rendered":"<p>\u05de\u05e6\u05d8\u05e2\u05e8\u05d9\u05dd, \u05e8\u05e9\u05d5\u05de\u05d4 \u05d6\u05d5 \u05d6\u05de\u05d9\u05e0\u05d4 \u05e8\u05e7 \u05d1- Espa\u00f1ol.D.Redondo \u2018Direni\u015f\u2019 -que en turco significa &quot;resistencia&quot;- es el eslogan de este a\u00f1o para la semana del Orgullo en Estambul. Las protestas contra la destruccion del parque Gezi, como emblema de la creceinte politica neoliberal de la politica del partido del gobierno y su tendencia a la restriccion de &hellip; <a href=\"https:\/\/www.rhythms-of-resistance.org\/he\/2013\/07\/09\/espanol-mas-orgullosas-que-nunca\/\" class=\"more-link\">\u05dc\u05d4\u05de\u05e9\u05d9\u05da \u05dc\u05e7\u05e8\u05d5\u05d0<span class=\"screen-reader-text\"> M\u00e1s orgullosas que nunca<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-170","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/www.rhythms-of-resistance.org\/he\/wp-json\/wp\/v2\/posts\/170"}],"collection":[{"href":"https:\/\/www.rhythms-of-resistance.org\/he\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rhythms-of-resistance.org\/he\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rhythms-of-resistance.org\/he\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rhythms-of-resistance.org\/he\/wp-json\/wp\/v2\/comments?post=170"}],"version-history":[{"count":1,"href":"https:\/\/www.rhythms-of-resistance.org\/he\/wp-json\/wp\/v2\/posts\/170\/revisions"}],"predecessor-version":[{"id":172,"href":"https:\/\/www.rhythms-of-resistance.org\/he\/wp-json\/wp\/v2\/posts\/170\/revisions\/172"}],"wp:attachment":[{"href":"https:\/\/www.rhythms-of-resistance.org\/he\/wp-json\/wp\/v2\/media?parent=170"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rhythms-of-resistance.org\/he\/wp-json\/wp\/v2\/categories?post=170"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rhythms-of-resistance.org\/he\/wp-json\/wp\/v2\/tags?post=170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}